{"id":6666,"date":"2024-04-19T20:23:34","date_gmt":"2024-04-19T19:23:34","guid":{"rendered":"https:\/\/saborealapalma.es\/?p=6666"},"modified":"2024-04-19T20:25:59","modified_gmt":"2024-04-19T19:25:59","slug":"los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid","status":"publish","type":"post","link":"https:\/\/saborealapalma.es\/de\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/","title":{"rendered":"Palmeran Produkte werden auf dem Sal\u00f3n Gourmets in Madrid beworben"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6666\" class=\"elementor elementor-6666\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6b8a763 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"6b8a763\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ef133e\" data-id=\"0ef133e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e17bf48 elementor-widget elementor-widget-text-editor\" data-id=\"e17bf48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><h4>Die Gesch\u00e4ftsf\u00fchrerin von Sodepal, Miriam Perestelo, betont, wie wichtig es ist, dass sich acht Lebensmittel- und Getr\u00e4nkehersteller aus La Palma bei einem der wichtigsten Treffen der Branche auf europ\u00e4ischer Ebene pr\u00e4sentieren.<\/h4><\/div><div class=\"field field--name-body field--type-text-with-summary field--label-hidden field--item\"><p>Das Cabildo de La Palma f\u00f6rdert \u00fcber das Projekt Saborea La Palma, das zum \u00f6ffentlichen Unternehmen Sodepal geh\u00f6rt, acht Unternehmen der Insel bei der 37. Ausgabe des Sal\u00f3n Gourmets, der f\u00fchrenden Lebensmittel- und Getr\u00e4nkemesse in Europa und der Welt, die vom 22. bis 25. April in Madrid stattfindet.<\/p><p>Die Stadtr\u00e4tin f\u00fcr Wirtschaftsf\u00f6rderung und Gesch\u00e4ftsf\u00fchrerin von Sodepal, Miriam Perestelo, betont, wie wichtig es ist, dass die Lebensmittel- und Getr\u00e4nkehersteller der Insel ihre Produkte auf einer Veranstaltung pr\u00e4sentieren, die als eine der ersten in Europa und als weltweite Referenz in Sachen Qualit\u00e4t gilt.<\/p><p>Zu diesem Zweck habe die Institution von La Palma gro\u00dfe Anstrengungen unternommen, um den Erzeugern und Rohstoffen der Insel die ihnen geb\u00fchrende Aufmerksamkeit zukommen zu lassen und sie bei anderen Fachleuten und Besuchern der Messe bekannt zu machen.<\/p><p>Die Veranstaltung wird von den Unternehmen Bodegas Tagalguen, Vinos Tendal, Veganorte, Ron Aldea, Delicias de La Huerta, Olicaf\u00e9, Bruco La Palma und der Asociaci\u00f3n de Criadores de Cabra Palmera pers\u00f6nlich besucht.<\/p><p>Die Marken Mojos Virginia, La Destiladera, Mojos Sicilia, Mojos Regina, Mojos Ricomo, Piedra Jurada, Bodegas Tamanca, Vitega und Vi\u00f1a Traviesa Vidaviva Ecofood, Ecofinca Tacande, Los Tumbitos und Los Barbuzanos Farmen, Ron Aldea, Isla Verde, Molino Las Bre\u00f1as, Molino El Guanche, Palmaoliva, Puros Julio und Salinas Tenegu\u00eda, die die Gelegenheit haben werden, ihre Produkte in einem eigens daf\u00fcr vorgesehenen Raum zu pr\u00e4sentieren. Hier haben die Besucher die M\u00f6glichkeit, die authentische Essenz von La Palma durch ihre Weine, landwirtschaftlichen Produkte, Kaffee, K\u00e4se und vieles mehr kennenzulernen und zu verkosten. \u00a0<\/p><p>Dar\u00fcber hinaus wird La Palma im Rahmen der Messe in der Sektion Oliven\u00f6le aus Spanien vertreten sein und dort die von Palmaoliva hergestellten \u00d6le ausstellen, um die Qualit\u00e4t und den charakteristischen Geschmack dieser Produkte hervorzuheben.<\/p><h4>Schmecken Sie La Palma<\/h4><p>Das Projekt Saborea La Palma zielt darauf ab, die Gastronomie von La Palma aufzuwerten und auf den regionalen, nationalen und internationalen M\u00e4rkten zu positionieren sowie die Erzeuger der Insel zu unterst\u00fctzen.<\/p><h4>Sal\u00f3n Gourmets<\/h4><p>Der Sal\u00f3n Gourmets feiert im Jahr 2024 seine 37. Ausgabe und positioniert sich als wichtige Messe zur F\u00f6rderung von Produzenten auf europ\u00e4ischer und weltweiter Ebene.<\/p><p>In diesem Jahr werden auf der Veranstaltung mehr als 2.000 Aussteller und 55.000 Produkte auf einer Fl\u00e4che von 65.000 Quadratmetern zu sehen sein. Dar\u00fcber hinaus werden 100.000 Fachbesucher aus 85 L\u00e4ndern erwartet.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Gesch\u00e4ftsf\u00fchrerin von Sodepal, Miriam Perestelo, betont, wie wichtig es ist, dass sich acht Lebensmittel- und Getr\u00e4nkeunternehmen aus La Palma bei einem der wichtigsten Treffen des Sektors auf europ\u00e4ischer Ebene pr\u00e4sentieren. Das Cabildo de La Palma hat \u00fcber das Projekt Saborea La Palma, das zum...<\/p>","protected":false},"author":4,"featured_media":6668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,21],"tags":[],"class_list":["post-6666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogsaborea","category-noticias-saborea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saborealapalma.es\/de\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma\" \/>\n<meta property=\"og:description\" content=\"La consejera delegada de Sodepal, Miriam Perestelo, destaca la importancia de que ocho empresas de alimentaci\u00f3n y bebida de La Palma se den a conocer en uno de los encuentros m\u00e1s importantes del sector a nivel europeo. El Cabildo de La Palma, a trav\u00e9s del proyecto Saborea La Palma, perteneciente...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saborealapalma.es\/de\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Saborea La Palma\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T19:23:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T19:25:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saborea La Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saborea La Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/\"},\"author\":{\"name\":\"Saborea La Palma\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\"},\"headline\":\"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid\",\"datePublished\":\"2024-04-19T19:23:34+00:00\",\"dateModified\":\"2024-04-19T19:25:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/\"},\"wordCount\":496,\"image\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/salon_gourmets.jpg\",\"articleSection\":[\"Blog Saborea\",\"Noticias Saborea\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/\",\"name\":\"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/salon_gourmets.jpg\",\"datePublished\":\"2024-04-19T19:23:34+00:00\",\"dateModified\":\"2024-04-19T19:25:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/salon_gourmets.jpg\",\"contentUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/salon_gourmets.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2024\\\/04\\\/19\\\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saborealapalma.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#website\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/\",\"name\":\"Saborea La Palma\",\"description\":\"Saborea La Palma es el proyecto que lidera la Sociedad de Promoci\u00f3n Econ\u00f3mica de La Palma (SODEPAL S.A.U.M.P), empresa p\u00fablica dependiente de Cabildo Insular de La Palma, para la revalorizaci\u00f3n y el posicionamiento de la gastronom\u00eda palmera en los mercados regionales, nacionales e internacionales.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saborealapalma.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\",\"name\":\"Saborea La Palma\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/de\\\/blog\\\/author\\\/ivcabeza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saborealapalma.es\/de\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/","og_locale":"de_DE","og_type":"article","og_title":"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma","og_description":"La consejera delegada de Sodepal, Miriam Perestelo, destaca la importancia de que ocho empresas de alimentaci\u00f3n y bebida de La Palma se den a conocer en uno de los encuentros m\u00e1s importantes del sector a nivel europeo. El Cabildo de La Palma, a trav\u00e9s del proyecto Saborea La Palma, perteneciente...","og_url":"https:\/\/saborealapalma.es\/de\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/","og_site_name":"Saborea La Palma","article_published_time":"2024-04-19T19:23:34+00:00","article_modified_time":"2024-04-19T19:25:59+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg","type":"image\/jpeg"}],"author":"Saborea La Palma","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Saborea La Palma","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#article","isPartOf":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/"},"author":{"name":"Saborea La Palma","@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc"},"headline":"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid","datePublished":"2024-04-19T19:23:34+00:00","dateModified":"2024-04-19T19:25:59+00:00","mainEntityOfPage":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/"},"wordCount":496,"image":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg","articleSection":["Blog Saborea","Noticias Saborea"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/","url":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/","name":"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid - Saborea La Palma","isPartOf":{"@id":"https:\/\/saborealapalma.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#primaryimage"},"image":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg","datePublished":"2024-04-19T19:23:34+00:00","dateModified":"2024-04-19T19:25:59+00:00","author":{"@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc"},"breadcrumb":{"@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#primaryimage","url":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg","contentUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2024\/04\/salon_gourmets.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/saborealapalma.es\/blog\/2024\/04\/19\/los-productos-palmeros-se-promocionan-en-el-salon-gourmets-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saborealapalma.es\/"},{"@type":"ListItem","position":2,"name":"Los productos palmeros se promocionan en el Sal\u00f3n Gourmets de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/saborealapalma.es\/#website","url":"https:\/\/saborealapalma.es\/","name":"Schmecken Sie La Palma","description":"Saborea La Palma ist das von der Sociedad de Promoci\u00f3n Econ\u00f3mica de La Palma (SODEPAL S.A.U.M.P), einem vom Cabildo Insular de La Palma abh\u00e4ngigen \u00f6ffentlichen Unternehmen, geleitete Projekt zur Aufwertung und Positionierung der Gastronomie La Palmas auf regionalen, nationalen und internationalen M\u00e4rkten.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saborealapalma.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc","name":"Schmecken Sie La Palma","url":"https:\/\/saborealapalma.es\/de\/blog\/author\/ivcabeza\/"}]}},"_links":{"self":[{"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/posts\/6666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/comments?post=6666"}],"version-history":[{"count":4,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/posts\/6666\/revisions"}],"predecessor-version":[{"id":6671,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/posts\/6666\/revisions\/6671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/media\/6668"}],"wp:attachment":[{"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/media?parent=6666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/categories?post=6666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saborealapalma.es\/de\/wp-json\/wp\/v2\/tags?post=6666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}