{"id":8830,"date":"2025-05-28T09:47:30","date_gmt":"2025-05-28T08:47:30","guid":{"rendered":"https:\/\/saborealapalma.es\/?p=8830"},"modified":"2025-05-28T09:53:04","modified_gmt":"2025-05-28T08:53:04","slug":"saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025","status":"publish","type":"post","link":"https:\/\/saborealapalma.es\/it\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/","title":{"rendered":"Saborea La Palma rafforza la sua strategia di internazionalizzazione al SALIMAT ABANCA 2025"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8830\" class=\"elementor elementor-8830\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6b8a763 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"6b8a763\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ef133e\" data-id=\"0ef133e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e17bf48 elementor-widget elementor-widget-text-editor\" data-id=\"e17bf48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><p>Il progetto Saborea La Palma, promosso dal Cabildo Insular de La Palma attraverso la societ\u00e0 pubblica Sodepal, parteciper\u00e0 dal 5 all'8 giugno alla fiera internazionale SALIMAT ABANCA 2025, che si terr\u00e0 nella citt\u00e0 galiziana di Silleda, nell'ambito della Settimana Verde della Galizia.<\/p><p>La presenza di La Palma a questa rinomata fiera agroalimentare mira a potenziare la promozione dei prodotti locali all'estero, a stabilire contatti commerciali e a incoraggiare l'apertura di nuovi mercati sulla terraferma. La partecipazione fa parte della strategia di posizionamento dell'isola come destinazione gastronomica con identit\u00e0, qualit\u00e0 e sostenibilit\u00e0.<\/p><p>Lo stand di Saborea La Palma avr\u00e0 un'attenta rappresentazione del settore agroalimentare dell'isola, con la presenza di cinque aziende invitate:<\/p><ul><li>Distillerie Aldea.<\/li><li>Richard Cigars.<\/li><li>Cantina Tagalguen.<\/li><li>Palmojo.<\/li><li>La Destiladera.<\/li><\/ul><p>Durante i giorni della fiera, i rappresentanti di questi marchi parteciperanno a incontri professionali, degustazioni, attivit\u00e0 di networking e presentazioni rivolte a distributori, acquirenti e media specializzati. Il marchio Saborea La Palma sar\u00e0 promosso anche come piattaforma per l'integrazione dei talenti gastronomici e agroalimentari dell'isola.<\/p><p>L'Assessore alla Promozione Economica del Consiglio dell'Isola di La Palma, Miriam Perestelo, ha sottolineato che \"la partecipazione a Salimat Abanca \u00e8 un'azione strategica che ci permette di continuare a consolidare il posizionamento del prodotto locale al di fuori delle Isole Canarie, generando reali opportunit\u00e0 di business per le nostre aziende e mostrando l'unicit\u00e0 della nostra isola come territorio dal sapore unico\".<\/p><p>Con questa azione, Saborea La Palma prosegue il suo piano di internazionalizzazione per il 2025, che prevede la partecipazione a fiere specializzate, la promozione nei mercati esteri e il sostegno al tessuto imprenditoriale agroalimentare di La Palma nel suo processo di crescita e diversificazione commerciale.<\/p><p>Maggiori informazioni su <a href=\"https:\/\/saborealapalma.es\/it\/ferias-en-las-que-hemos-estado\/salimat-abanca-2025\/\" target=\"_blank\" rel=\"noopener\">Assaggi La Palma in Salimat Abanca 2025<\/a><\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Il progetto Saborea La Palma, promosso dal Cabildo Insular de La Palma attraverso la societ\u00e0 pubblica Sodepal, parteciper\u00e0 dal 5 all'8 giugno alla fiera internazionale SALIMAT ABANCA 2025, che si terr\u00e0 nella citt\u00e0 galiziana di Silleda, nell'ambito della Semana Verde...<\/p>","protected":false},"author":4,"featured_media":8832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,21],"tags":[],"class_list":["post-8830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogsaborea","category-noticias-saborea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saborealapalma.es\/it\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma\" \/>\n<meta property=\"og:description\" content=\"El proyecto Saborea La Palma, promovido por el Cabildo Insular de La Palma a trav\u00e9s de la empresa p\u00fablica Sodepal, participar\u00e1 del 5 al 8 de junio en la feria internacional SALIMAT ABANCA 2025, que se celebra en la localidad gallega de Silleda, en el marco de la Semana Verde...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saborealapalma.es\/it\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Saborea La Palma\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T08:47:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T08:53:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saborea La Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saborea La Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/\"},\"author\":{\"name\":\"Saborea La Palma\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\"},\"headline\":\"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025\",\"datePublished\":\"2025-05-28T08:47:30+00:00\",\"dateModified\":\"2025-05-28T08:53:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/\"},\"wordCount\":323,\"image\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Stand_Salimat25_c-2.jpg\",\"articleSection\":[\"Blog Saborea\",\"Noticias Saborea\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/\",\"name\":\"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Stand_Salimat25_c-2.jpg\",\"datePublished\":\"2025-05-28T08:47:30+00:00\",\"dateModified\":\"2025-05-28T08:53:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Stand_Salimat25_c-2.jpg\",\"contentUrl\":\"https:\\\/\\\/saborealapalma.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Stand_Salimat25_c-2.jpg\",\"width\":1280,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/blog\\\/2025\\\/05\\\/28\\\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saborealapalma.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#website\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/\",\"name\":\"Saborea La Palma\",\"description\":\"Saborea La Palma es el proyecto que lidera la Sociedad de Promoci\u00f3n Econ\u00f3mica de La Palma (SODEPAL S.A.U.M.P), empresa p\u00fablica dependiente de Cabildo Insular de La Palma, para la revalorizaci\u00f3n y el posicionamiento de la gastronom\u00eda palmera en los mercados regionales, nacionales e internacionales.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saborealapalma.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/saborealapalma.es\\\/#\\\/schema\\\/person\\\/5184c05828c0a459bbca73a6b4e6b4dc\",\"name\":\"Saborea La Palma\",\"url\":\"https:\\\/\\\/saborealapalma.es\\\/it\\\/blog\\\/author\\\/ivcabeza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saborealapalma.es\/it\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma","og_description":"El proyecto Saborea La Palma, promovido por el Cabildo Insular de La Palma a trav\u00e9s de la empresa p\u00fablica Sodepal, participar\u00e1 del 5 al 8 de junio en la feria internacional SALIMAT ABANCA 2025, que se celebra en la localidad gallega de Silleda, en el marco de la Semana Verde...","og_url":"https:\/\/saborealapalma.es\/it\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/","og_site_name":"Saborea La Palma","article_published_time":"2025-05-28T08:47:30+00:00","article_modified_time":"2025-05-28T08:53:04+00:00","og_image":[{"width":1280,"height":1600,"url":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg","type":"image\/jpeg"}],"author":"Saborea La Palma","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Saborea La Palma","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#article","isPartOf":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/"},"author":{"name":"Saborea La Palma","@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc"},"headline":"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025","datePublished":"2025-05-28T08:47:30+00:00","dateModified":"2025-05-28T08:53:04+00:00","mainEntityOfPage":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/"},"wordCount":323,"image":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg","articleSection":["Blog Saborea","Noticias Saborea"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/","url":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/","name":"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025 - Saborea La Palma","isPartOf":{"@id":"https:\/\/saborealapalma.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#primaryimage"},"image":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg","datePublished":"2025-05-28T08:47:30+00:00","dateModified":"2025-05-28T08:53:04+00:00","author":{"@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc"},"breadcrumb":{"@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#primaryimage","url":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg","contentUrl":"https:\/\/saborealapalma.es\/wp-content\/uploads\/2025\/05\/Stand_Salimat25_c-2.jpg","width":1280,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/saborealapalma.es\/blog\/2025\/05\/28\/saborea-la-palma-refuerza-su-estrategia-de-internacionalizacion-en-salimat-abanca-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saborealapalma.es\/"},{"@type":"ListItem","position":2,"name":"Saborea La Palma refuerza su estrategia de internacionalizaci\u00f3n en SALIMAT ABANCA 2025"}]},{"@type":"WebSite","@id":"https:\/\/saborealapalma.es\/#website","url":"https:\/\/saborealapalma.es\/","name":"Assaggia La Palma","description":"Saborea La Palma \u00e8 il progetto guidato dalla Sociedad de Promoci\u00f3n Econ\u00f3mica de La Palma (SODEPAL S.A.U.M.P), una societ\u00e0 pubblica dipendente dal Cabildo Insular de La Palma, per la rivalutazione e il posizionamento della gastronomia di La Palma nei mercati regionali, nazionali e internazionali.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saborealapalma.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/saborealapalma.es\/#\/schema\/person\/5184c05828c0a459bbca73a6b4e6b4dc","name":"Assaggia La Palma","url":"https:\/\/saborealapalma.es\/it\/blog\/author\/ivcabeza\/"}]}},"_links":{"self":[{"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/posts\/8830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/comments?post=8830"}],"version-history":[{"count":10,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/posts\/8830\/revisions"}],"predecessor-version":[{"id":8841,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/posts\/8830\/revisions\/8841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/media\/8832"}],"wp:attachment":[{"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/media?parent=8830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/categories?post=8830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saborealapalma.es\/it\/wp-json\/wp\/v2\/tags?post=8830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}